{"id":314,"count":7,"description":"","link":"https:\/\/nuba.com\/en\/blog\/tag\/indonesia-en\/","name":"Indonesia","slug":"indonesia-en","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Discover the best articles about Indonesia and learn all about travel, adventures, destinations, experiences and much more with NUBA&#039;s Blog.\" \/>\n\t<meta name=\"robots\" content=\"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/nuba.com\/en\/blog\/tag\/indonesia-en\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"NUBA -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Articles about Indonesia - Blog NUBA\" \/>\n\t\t<meta property=\"og:description\" content=\"Discover the best articles about Indonesia and learn all about travel, adventures, destinations, experiences and much more with NUBA&#039;s Blog.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/nuba.com\/en\/blog\/tag\/indonesia-en\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/nuba.com\/wp-content\/uploads\/2025\/02\/Logo-Nuba-Generico_Negro.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/nuba.com\/wp-content\/uploads\/2025\/02\/Logo-Nuba-Generico_Negro.svg\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Articles about Indonesia - Blog NUBA\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Discover the best articles about Indonesia and learn all about travel, adventures, destinations, experiences and much more with NUBA&#039;s Blog.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/nuba.com\/wp-content\/uploads\/2025\/02\/Logo-Nuba-Generico_Negro.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/314\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuba.com\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/blog\\\/tag\\\/indonesia-en\\\/#listItem\",\"name\":\"Indonesia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/blog\\\/tag\\\/indonesia-en\\\/#listItem\",\"position\":2,\"name\":\"Indonesia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/314\\\/#collectionpage\",\"url\":\"https:\\\/\\\/nuba.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/314\\\/\",\"name\":\"Articles about Indonesia - Blog NUBA\",\"description\":\"Discover the best articles about Indonesia and learn all about travel, adventures, destinations, experiences and much more with NUBA's Blog.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/314\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/#organization\",\"name\":\"NUBA\",\"url\":\"https:\\\/\\\/nuba.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nuba.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Logo-Nuba-Generico_Negro.svg\",\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/314\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/314\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/nuba.com\\\/en\\\/\",\"name\":\"NUBA\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuba.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Articles about Indonesia - Blog NUBA<\/title>\n\n","aioseo_head_json":{"title":"Articles about Indonesia - Blog NUBA","description":"Discover the best articles about Indonesia and learn all about travel, adventures, destinations, experiences and much more with NUBA's Blog.","canonical_url":"https:\/\/nuba.com\/en\/blog\/tag\/indonesia-en\/","robots":"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/nuba.com\/en\/wp-json\/wp\/v2\/tags\/314\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nuba.com\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/nuba.com\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nuba.com\/en\/blog\/tag\/indonesia-en\/#listItem","name":"Indonesia"}},{"@type":"ListItem","@id":"https:\/\/nuba.com\/en\/blog\/tag\/indonesia-en\/#listItem","position":2,"name":"Indonesia","previousItem":{"@type":"ListItem","@id":"https:\/\/nuba.com\/en\/#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/nuba.com\/en\/wp-json\/wp\/v2\/tags\/314\/#collectionpage","url":"https:\/\/nuba.com\/en\/wp-json\/wp\/v2\/tags\/314\/","name":"Articles about Indonesia - Blog NUBA","description":"Discover the best articles about Indonesia and learn all about travel, adventures, destinations, experiences and much more with NUBA's Blog.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/nuba.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/nuba.com\/en\/wp-json\/wp\/v2\/tags\/314\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/nuba.com\/en\/#organization","name":"NUBA","url":"https:\/\/nuba.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/nuba.com\/wp-content\/uploads\/2025\/02\/Logo-Nuba-Generico_Negro.svg","@id":"https:\/\/nuba.com\/en\/wp-json\/wp\/v2\/tags\/314\/#organizationLogo"},"image":{"@id":"https:\/\/nuba.com\/en\/wp-json\/wp\/v2\/tags\/314\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/nuba.com\/en\/#website","url":"https:\/\/nuba.com\/en\/","name":"NUBA","inLanguage":"en-US","publisher":{"@id":"https:\/\/nuba.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"NUBA -","og:type":"article","og:title":"Articles about Indonesia - Blog NUBA","og:description":"Discover the best articles about Indonesia and learn all about travel, adventures, destinations, experiences and much more with NUBA's Blog.","og:url":"https:\/\/nuba.com\/en\/blog\/tag\/indonesia-en\/","og:image":"https:\/\/nuba.com\/wp-content\/uploads\/2025\/02\/Logo-Nuba-Generico_Negro.svg","og:image:secure_url":"https:\/\/nuba.com\/wp-content\/uploads\/2025\/02\/Logo-Nuba-Generico_Negro.svg","twitter:card":"summary_large_image","twitter:title":"Articles about Indonesia - Blog NUBA","twitter:description":"Discover the best articles about Indonesia and learn all about travel, adventures, destinations, experiences and much more with NUBA's Blog.","twitter:image":"https:\/\/nuba.com\/wp-content\/uploads\/2025\/02\/Logo-Nuba-Generico_Negro.svg"},"aioseo_meta_data":{"term_id":"314","title":null,"description":null,"keywords":null,"keyphrases":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"pillar_content":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"tabs":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 11:40:39","breadcrumb_settings":null,"created":"2025-10-13 19:27:14","updated":"2026-05-13 11:40:39","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/nuba.com\/en\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\tIndonesia\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/nuba.com\/en\/"},{"label":"Indonesia","link":"https:\/\/nuba.com\/en\/blog\/tag\/indonesia-en\/"}],"_links":{"self":[{"href":"https:\/\/nuba.com\/en\/wp-json\/wp\/v2\/tags\/314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuba.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/nuba.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/nuba.com\/en\/wp-json\/wp\/v2\/posts?tags=314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}